{"id":2855,"date":"2023-03-11T04:45:15","date_gmt":"2023-03-11T04:45:15","guid":{"rendered":"https:\/\/ojs.org.uk\/website\/live\/?page_id=2855"},"modified":"2025-07-07T17:48:53","modified_gmt":"2025-07-07T17:48:53","slug":"trial-application-form","status":"publish","type":"page","link":"https:\/\/ojs.org.uk\/website\/live\/en\/trial-application-form\/","title":{"rendered":"Trial Application Form"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div class=\"text-black-60 quote mb-4\">\n<p>Please note that data you provide will be used for the purpose of processing your application. Data submitted will be deleted after the trial lesson but anonymised data may be retained in accordance with our<br \/>\n<a href=\"https:\/\/ojs.org.uk\/website\/live2\/wp-content\/themes\/OJS_Theme\/img\/OJS-Data-Protection-Policy.pdf\">data protection policy.<\/a>\n<\/div>\n<p>Please check your mail application setting to ensure that you can receive our reply email from @ojs.org.uk address, and fill out and submit this form to apply for a free trial lesson.\u3000(<span style=\"color: #ff0000;\">*<\/span> indicates a mandatory field.)<\/p>\n<p>The information submitted via this form will be discarded upon completion of the trial lesson.<\/p>\n<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-2860\"><form id=\"wpforms-form-2860\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"2860\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/website\/live\/en\/wp-json\/wp\/v2\/pages\/2855\" data-token=\"d125a0b6f7b52cb1fd2bbac5db290f76\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-2860-field_1-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-2860-field_1\">Pupil&#039;s Name <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-2860-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" required><\/div><div id=\"wpforms-2860-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-2860-field_3\">Date of Birth <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-2860-field_3\" class=\"wpforms-field-small wpforms-field-required\" name=\"wpforms[fields][3]\" required><\/div><div id=\"wpforms-2860-field_4-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-2860-field_4\">UK School Year <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-2860-field_4\" class=\"wpforms-field-small wpforms-field-required\" name=\"wpforms[fields][4]\" required><\/div><div id=\"wpforms-2860-field_5-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-2860-field_5\">Parent\/Guardian&#039;s Name <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-2860-field_5\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][5]\" required><\/div><div id=\"wpforms-2860-field_20-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"20\"><label class=\"wpforms-field-label\" for=\"wpforms-2860-field_20\">Parent\/Guardian&#039;s Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-2860-field_20\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][20]\" required><\/div><div id=\"wpforms-2860-field_22-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"22\"><label class=\"wpforms-field-label\" for=\"wpforms-2860-field_22\">Parent\/Guardian&#039;s mobile number<\/label><input type=\"text\" id=\"wpforms-2860-field_22\" class=\"wpforms-field-medium\" name=\"wpforms[fields][22]\" ><\/div><div id=\"wpforms-2860-field_9-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-2860-field_9\">Main reason for wishing to join the Japanese School <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-2860-field_9\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][9]\" required><\/textarea><\/div><div id=\"wpforms-2860-field_12-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-inline\" data-field-id=\"12\"><label class=\"wpforms-field-label\" for=\"wpforms-2860-field_12\">Can read Hiragana? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-2860-field_12\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-2860-field_12_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][12][]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2860-field_12_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-2860-field_12_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][12][]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2860-field_12_2\">No<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-2860-field_12_3\" data-rule-check-limit=\"true\" name=\"wpforms[fields][12][]\" value=\"A little\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2860-field_12_3\">A little<\/label><\/li><\/ul><\/div><div id=\"wpforms-2860-field_26-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-inline\" data-field-id=\"26\"><label class=\"wpforms-field-label\" for=\"wpforms-2860-field_26\">Can write Hiragana?  <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-2860-field_26\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-2860-field_26_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][26][]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2860-field_26_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-2860-field_26_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][26][]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2860-field_26_2\">No<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-2860-field_26_3\" data-rule-check-limit=\"true\" name=\"wpforms[fields][26][]\" value=\"A little\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2860-field_26_3\">A little<\/label><\/li><\/ul><\/div><div id=\"wpforms-2860-field_13-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-inline\" data-field-id=\"13\"><label class=\"wpforms-field-label\" for=\"wpforms-2860-field_13\">Can read Katakana? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-2860-field_13\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-2860-field_13_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][13][]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2860-field_13_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-2860-field_13_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][13][]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2860-field_13_2\">No<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-2860-field_13_3\" data-rule-check-limit=\"true\" name=\"wpforms[fields][13][]\" value=\"A little\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2860-field_13_3\">A little<\/label><\/li><\/ul><\/div><div id=\"wpforms-2860-field_27-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-inline\" data-field-id=\"27\"><label class=\"wpforms-field-label\" for=\"wpforms-2860-field_27\">Can write Katakana? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-2860-field_27\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-2860-field_27_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][27][]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2860-field_27_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-2860-field_27_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][27][]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2860-field_27_2\">No<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-2860-field_27_3\" data-rule-check-limit=\"true\" name=\"wpforms[fields][27][]\" value=\"A little\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2860-field_27_3\">A little<\/label><\/li><\/ul><\/div><div id=\"wpforms-2860-field_14-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-inline\" data-field-id=\"14\"><label class=\"wpforms-field-label\" for=\"wpforms-2860-field_14\">Can speak Japanese? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-2860-field_14\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-2860-field_14_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][14][]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2860-field_14_1\">No<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-2860-field_14_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][14][]\" value=\"Basic\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2860-field_14_2\">Basic<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-2860-field_14_3\" data-rule-check-limit=\"true\" name=\"wpforms[fields][14][]\" value=\"Fluent\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2860-field_14_3\">Fluent<\/label><\/li><\/ul><\/div><div id=\"wpforms-2860-field_24-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"24\"><label class=\"wpforms-field-label\" for=\"wpforms-2860-field_24\">The main language and secondary language used at home <\/label><input type=\"text\" id=\"wpforms-2860-field_24\" class=\"wpforms-field-medium\" name=\"wpforms[fields][24]\" ><\/div><div id=\"wpforms-2860-field_19-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"19\"><label class=\"wpforms-field-label\" for=\"wpforms-2860-field_19\">Please list the names and the class names of currently enrolled siblings if applicable.<\/label><textarea id=\"wpforms-2860-field_19\" class=\"wpforms-field-medium\" name=\"wpforms[fields][19]\" ><\/textarea><\/div><div id=\"wpforms-2860-field_28-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"28\"><label class=\"wpforms-field-label\" for=\"wpforms-2860-field_28\">Any other information you would like us to be aware of. (e.g. medical condition, food and other allergies etc)<\/label><textarea id=\"wpforms-2860-field_28\" class=\"wpforms-field-medium\" name=\"wpforms[fields][28]\" ><\/textarea><\/div><\/div><div class=\"wpforms-submit-container\"><input type=\"hidden\" name=\"wpforms[id]\" value=\"2860\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-2860\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ojs.org.uk\/website\/live\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Please note that data you provide will be used for the purpose of processing your application. Data sub [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_locale":"en_GB","_original_post":"https:\/\/ojs.org.uk\/website\/live2\/?page_id=73","footnotes":""},"class_list":["post-2855","page","type-page","status-publish","hentry","en-GB"],"_links":{"self":[{"href":"https:\/\/ojs.org.uk\/website\/live\/wp-json\/wp\/v2\/pages\/2855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ojs.org.uk\/website\/live\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ojs.org.uk\/website\/live\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ojs.org.uk\/website\/live\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ojs.org.uk\/website\/live\/wp-json\/wp\/v2\/comments?post=2855"}],"version-history":[{"count":31,"href":"https:\/\/ojs.org.uk\/website\/live\/wp-json\/wp\/v2\/pages\/2855\/revisions"}],"predecessor-version":[{"id":3721,"href":"https:\/\/ojs.org.uk\/website\/live\/wp-json\/wp\/v2\/pages\/2855\/revisions\/3721"}],"wp:attachment":[{"href":"https:\/\/ojs.org.uk\/website\/live\/wp-json\/wp\/v2\/media?parent=2855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}